{"id":6,"count":0,"description":"Il sito web dell'Infoshop di Laurentinokkupato nasce contemporaneamente al resto del sito nell'aprile 1995, ne \u00e8 anzi, fin dall'inizio, la parte pi\u00f9 corposa. Abbiamo subito visto il World Wide Web come il mezzo ideale per far circolare idee, e informazioni, che superava i limiti di circolazione e distribuzione. Qualcuno di noi si \u00e8 impegnato nell'impratichirsi con Internet, e-mail &amp; co. e soprattutto nello studiare come costruire il sito, ossia imparare il linguaggio HTML (all'epoca c'era da imparare HTML 2).\r\n\r\nCos\u00ec adesso, dopo anni di costante cura, il sito di Laurentinokkupato \u00e8 ricco di informazioni e produzioni che prima era possibile avere solo riuscendo a mettere materialmente le mani su una fotocopia trovata in un CSOA o cose simili.\r\nOggi, per chi ha un collegamento ad Internet, l'Infoshop \u00e8 aperto 24 ore su 24, non ci sono spese di spedizione o altro e chiunque pu\u00f2 prendere e ristampare nel proprio territorio le nostre autoproduzioni e distribuzioni.","link":"https:\/\/l38squat.noblogs.org\/pt\/post\/category\/infoshop\/","name":"Infoshop","slug":"infoshop","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/l38squat.noblogs.org\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/l38squat.noblogs.org\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/l38squat.noblogs.org\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/l38squat.noblogs.org\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}